{"id":4192,"date":"2019-07-20T14:21:06","date_gmt":"2019-07-20T14:21:06","guid":{"rendered":"https:\/\/cochamo.com\/eco-hostal-las-bandurrias\/"},"modified":"2021-12-11T21:37:25","modified_gmt":"2021-12-11T21:37:25","slug":"las-bandurrias-hospedaje-cochamo","status":"publish","type":"post","link":"https:\/\/cochamo.com\/en\/las-bandurrias-hospedaje-cochamo\/","title":{"rendered":"Eco Hostal Las Bandurrias"},"content":{"rendered":"<p>El hostal familiar Bandurrias est\u00e1 ubicado en lo alto del sector El Bosque. Rodeado de incre\u00edbles vistas del estuario y cerros Yates y Osorno. <\/p>\n\n\n\n<p>Manejado por una pareja suizo-chilena. Hablan espa\u00f1ol, ingl\u00e9s, franc\u00e9s y alem\u00e1n. Les podr\u00e1n brindar recomendaciones para explorar la zona y se sentir\u00e1n en casa en su hostal. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/webmium.blob.core.windows.net\/users\/81020\/assets\/fca2296623034e2cc6e740f278c7fb5b\/dsc5703.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Contactarse con sus due\u00f1os para consultar por tarifas. <\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d27625.573542408874!2d-72.29015514313623!3d-41.485456660128754!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x9619eacd3dc9676f%3A0xe863021d21ef5f9d!2sLas%20Bandurrias%20Eco%20Hostal%20-%20Cocham%C3%B3!5e0!3m2!1sen!2sar!4v1566838685328!5m2!1sen!2sar\" style=\"border:0;\" allowfullscreen=\"\" width=\"100%\" height=\"450\" frameborder=\"0\"><\/iframe>\n\n\n\n<p><i class=\"fa fa-phone\" ><\/i> : <a href=\"\/en\/+56996722590\/\">+56 (9) 9672-2590<\/a><br><i class=\"fa fa-at\" ><\/i> <a href=\"mailto:hostalbandurrias@gmail.com\">hostalbandurrias@gmail.com<\/a><br><i class=\"fa fa-desktop\" ><\/i> <a rel=\"noreferrer noopener\" aria-label=\"HostalBandurrias.com\/en\/ (opens in a new tab)\" href=\"http:\/\/www.hostalbandurrias.com\/en\/\" target=\"_blank\">HostalBandurrias.com\/en\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Rodeado de incre\u00edbles vistas del estuario y cerros Yates y Osorno. Manejado por una pareja suizo-chilena. Hablan espa\u00f1ol, ingl\u00e9s, franc\u00e9s y alem\u00e1n. Les podr\u00e1n brindar recomendaciones para explorar la zona y se sentir\u00e1n en casa en su hostal. <\/p>","protected":false},"author":1,"featured_media":3286,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[457,456],"tags":[106,107],"class_list":["post-4192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hospedaje-destacado","category-hospedaje-cochamo","tag-bandurrias-cochamo","tag-hostal-bandurrias-cochamo"],"jetpack_featured_media_url":"https:\/\/cochamo.com\/wp-content\/uploads\/2019\/08\/town_hostal-bandurias.jpg","_links":{"self":[{"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/posts\/4192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/comments?post=4192"}],"version-history":[{"count":3,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/posts\/4192\/revisions"}],"predecessor-version":[{"id":8237,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/posts\/4192\/revisions\/8237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/media\/3286"}],"wp:attachment":[{"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/media?parent=4192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/categories?post=4192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cochamo.com\/en\/wp-json\/wp\/v2\/tags?post=4192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}